{"id":158,"date":"2020-11-03T13:40:44","date_gmt":"2020-11-03T12:40:44","guid":{"rendered":"https:\/\/www.kerarqueo.com\/?post_type=product&#038;p=158"},"modified":"2021-03-05T10:20:32","modified_gmt":"2021-03-05T09:20:32","slug":"venus-de-brassempouy","status":"publish","type":"product","link":"https:\/\/www.kerarqueo.com\/producto\/venus-de-brassempouy\/","title":{"rendered":"Venus de Brassempouy"},"content":{"rendered":"<p><strong>Cronolog\u00eda<\/strong>: Paleol\u00edtico Superior, Gravetiense (26000 &#8211; 24000 BP)<br \/>\n<strong>Procedencia<\/strong>: Sur de Francia, excavaci\u00f3n en \u201cla cueva del Papa\u201d<br \/>\n<strong>Original<\/strong>: Museo de Saint-Germain-en-Laye (Par\u00eds)<br \/>\n<strong>Uso:<\/strong>\u00a0Ritual<br \/>\n<strong>Medidas reproducci\u00f3n:<\/strong> anchura 3 cm, altura 5 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Tama\u00f1o<\/strong>: 3&#215;5 cm<\/p>\n","protected":false},"featured_media":346,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_mi_skip_tracking":false},"product_cat":[21],"product_tag":[26,39,27,25,31],"_links":{"self":[{"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/product\/158"}],"collection":[{"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/comments?post=158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/media\/346"}],"wp:attachment":[{"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/media?parent=158"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/product_cat?post=158"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kerarqueo.com\/wp-json\/wp\/v2\/product_tag?post=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}